{"id":16515,"date":"2024-03-07T06:12:00","date_gmt":"2024-03-07T06:12:00","guid":{"rendered":"https:\/\/www.mid-electronique.com\/produit\/regulateur-gefran-1000-r0-2r-0-1-gefran-5"},"modified":"2025-04-22T04:35:03","modified_gmt":"2025-04-22T04:35:03","slug":"regulateur-gefran-1000-r0-2r-0-1-gefran-5","status":"publish","type":"product","link":"https:\/\/www.mid-electronique.com\/es\/produit\/regulateur-gefran-1000-r0-2r-0-1-gefran-5","title":{"rendered":"REGULATEUR GEFRAN 1000-R0-2R-0-1 GEFRAN"},"content":{"rendered":"<p>REGULATEUR GEFRAN 1000-R0-2R-0-1 GEFRAN : pour faciliter vos demandes de devis, si vous avez besoin d\u2019autres \u00e9quipements \u00e9lectroniques, vous pouvez constituer un panier et nous pourrons chiffrer l\u2019ensemble du mat\u00e9riel souhait\u00e9. De plus, si vous avez besoin de r\u00e9paration sur un \u00e9quipement REGULATEUR GEFRAN 1000-R0-2R-0-1 GEFRAN, contactez-nous. MID Electronique g\u00e8re l&#8217;obsolescence de ce mat\u00e9riel :REGULATEUR GEFRAN 1000-R0-2R-0-1 GEFRAN<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGULATEUR GEFRAN 1000-R0-2R-0-1 GEFRAN : pour obtenir un devis gratuit, le d\u00e9lai livraison, et la dur\u00e9e de garantie, merci de remplir ci-dessous le formulaire Demande de devis. MID Electronique \u00e9tant expert en gestion de l\u2019obsolescence et MCO, contactez-nous pour de la maintenance de REGULATEUR GEFRAN 1000-R0-2R-0-1 GEFRAN ou de la r\u00e9paration de REGULATEUR GEFRAN 1000-R0-2R-0-1 GEFRAN<\/p>\n","protected":false},"featured_media":21061,"template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false},"pwb-brand":[35],"product_brand":[],"product_cat":[80],"product_tag":[],"class_list":{"0":"post-16515","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"pwb-brand-gefran","7":"product_cat-regulateur","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>REGULATEUR GEFRAN 1000-R0-2R-0-1 GEFRAN - MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO<\/title>\n<meta name=\"description\" content=\"REGULATEUR GEFRAN 1000-R0-2R-0-1 GEFRAN : devis gratuit, d\u00e9lai livraison, dur\u00e9e garantie sur simple demande \u00e0 MID Electronique expert MCO\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mid-electronique.com\/es\/produit\/regulateur-gefran-1000-r0-2r-0-1-gefran-5\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"REGULATEUR GEFRAN 1000-R0-2R-0-1 GEFRAN - MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO\" \/>\n<meta property=\"og:description\" content=\"REGULATEUR GEFRAN 1000-R0-2R-0-1 GEFRAN : devis gratuit, d\u00e9lai livraison, dur\u00e9e garantie sur simple demande \u00e0 MID Electronique expert MCO\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mid-electronique.com\/es\/produit\/regulateur-gefran-1000-r0-2r-0-1-gefran-5\" \/>\n<meta property=\"og:site_name\" content=\"MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-22T04:35:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mid-electronique.com\/wp-content\/uploads\/2023\/11\/logo-MID-Electronique.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"213\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mid-electronique.com\/es\/produit\/regulateur-gefran-1000-r0-2r-0-1-gefran-5\",\"url\":\"https:\/\/www.mid-electronique.com\/es\/produit\/regulateur-gefran-1000-r0-2r-0-1-gefran-5\",\"name\":\"REGULATEUR GEFRAN 1000-R0-2R-0-1 GEFRAN - MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO\",\"isPartOf\":{\"@id\":\"https:\/\/www.mid-electronique.com\/es#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mid-electronique.com\/es\/produit\/regulateur-gefran-1000-r0-2r-0-1-gefran-5#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.mid-electronique.com\/es\/produit\/regulateur-gefran-1000-r0-2r-0-1-gefran-5#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mid-electronique.com\/wp-content\/uploads\/2025\/04\/Materiel-electronique-neuf-et-occasion-MID-Electronique.jpg\",\"datePublished\":\"2024-03-07T06:12:00+00:00\",\"dateModified\":\"2025-04-22T04:35:03+00:00\",\"description\":\"REGULATEUR GEFRAN 1000-R0-2R-0-1 GEFRAN : devis gratuit, d\u00e9lai livraison, dur\u00e9e garantie sur simple demande \u00e0 MID Electronique expert MCO\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mid-electronique.com\/es\/produit\/regulateur-gefran-1000-r0-2r-0-1-gefran-5#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mid-electronique.com\/es\/produit\/regulateur-gefran-1000-r0-2r-0-1-gefran-5\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.mid-electronique.com\/es\/produit\/regulateur-gefran-1000-r0-2r-0-1-gefran-5#primaryimage\",\"url\":\"https:\/\/www.mid-electronique.com\/wp-content\/uploads\/2025\/04\/Materiel-electronique-neuf-et-occasion-MID-Electronique.jpg\",\"contentUrl\":\"https:\/\/www.mid-electronique.com\/wp-content\/uploads\/2025\/04\/Materiel-electronique-neuf-et-occasion-MID-Electronique.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mid-electronique.com\/es\/produit\/regulateur-gefran-1000-r0-2r-0-1-gefran-5#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.mid-electronique.com\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\/\/www.mid-electronique.com\/boutique\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"REGULATEUR GEFRAN 1000-R0-2R-0-1 GEFRAN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mid-electronique.com\/es#website\",\"url\":\"https:\/\/www.mid-electronique.com\/es\",\"name\":\"MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.mid-electronique.com\/es#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mid-electronique.com\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.mid-electronique.com\/es#organization\",\"name\":\"MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO\",\"url\":\"https:\/\/www.mid-electronique.com\/es\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.mid-electronique.com\/es#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.mid-electronique.com\/wp-content\/uploads\/2023\/11\/logo-MID-Electronique.png\",\"contentUrl\":\"https:\/\/www.mid-electronique.com\/wp-content\/uploads\/2023\/11\/logo-MID-Electronique.png\",\"width\":300,\"height\":213,\"caption\":\"MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO\"},\"image\":{\"@id\":\"https:\/\/www.mid-electronique.com\/es#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/fr.linkedin.com\/company\/mid-electronique\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"REGULATEUR GEFRAN 1000-R0-2R-0-1 GEFRAN - MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO","description":"REGULATEUR GEFRAN 1000-R0-2R-0-1 GEFRAN : devis gratuit, d\u00e9lai livraison, dur\u00e9e garantie sur simple demande \u00e0 MID Electronique expert MCO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mid-electronique.com\/es\/produit\/regulateur-gefran-1000-r0-2r-0-1-gefran-5","og_locale":"es_ES","og_type":"article","og_title":"REGULATEUR GEFRAN 1000-R0-2R-0-1 GEFRAN - MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO","og_description":"REGULATEUR GEFRAN 1000-R0-2R-0-1 GEFRAN : devis gratuit, d\u00e9lai livraison, dur\u00e9e garantie sur simple demande \u00e0 MID Electronique expert MCO","og_url":"https:\/\/www.mid-electronique.com\/es\/produit\/regulateur-gefran-1000-r0-2r-0-1-gefran-5","og_site_name":"MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO","article_modified_time":"2025-04-22T04:35:03+00:00","og_image":[{"width":300,"height":213,"url":"https:\/\/www.mid-electronique.com\/wp-content\/uploads\/2023\/11\/logo-MID-Electronique.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mid-electronique.com\/es\/produit\/regulateur-gefran-1000-r0-2r-0-1-gefran-5","url":"https:\/\/www.mid-electronique.com\/es\/produit\/regulateur-gefran-1000-r0-2r-0-1-gefran-5","name":"REGULATEUR GEFRAN 1000-R0-2R-0-1 GEFRAN - MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO","isPartOf":{"@id":"https:\/\/www.mid-electronique.com\/es#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mid-electronique.com\/es\/produit\/regulateur-gefran-1000-r0-2r-0-1-gefran-5#primaryimage"},"image":{"@id":"https:\/\/www.mid-electronique.com\/es\/produit\/regulateur-gefran-1000-r0-2r-0-1-gefran-5#primaryimage"},"thumbnailUrl":"https:\/\/www.mid-electronique.com\/wp-content\/uploads\/2025\/04\/Materiel-electronique-neuf-et-occasion-MID-Electronique.jpg","datePublished":"2024-03-07T06:12:00+00:00","dateModified":"2025-04-22T04:35:03+00:00","description":"REGULATEUR GEFRAN 1000-R0-2R-0-1 GEFRAN : devis gratuit, d\u00e9lai livraison, dur\u00e9e garantie sur simple demande \u00e0 MID Electronique expert MCO","breadcrumb":{"@id":"https:\/\/www.mid-electronique.com\/es\/produit\/regulateur-gefran-1000-r0-2r-0-1-gefran-5#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mid-electronique.com\/es\/produit\/regulateur-gefran-1000-r0-2r-0-1-gefran-5"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mid-electronique.com\/es\/produit\/regulateur-gefran-1000-r0-2r-0-1-gefran-5#primaryimage","url":"https:\/\/www.mid-electronique.com\/wp-content\/uploads\/2025\/04\/Materiel-electronique-neuf-et-occasion-MID-Electronique.jpg","contentUrl":"https:\/\/www.mid-electronique.com\/wp-content\/uploads\/2025\/04\/Materiel-electronique-neuf-et-occasion-MID-Electronique.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.mid-electronique.com\/es\/produit\/regulateur-gefran-1000-r0-2r-0-1-gefran-5#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.mid-electronique.com\/es"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/www.mid-electronique.com\/boutique"},{"@type":"ListItem","position":3,"name":"REGULATEUR GEFRAN 1000-R0-2R-0-1 GEFRAN"}]},{"@type":"WebSite","@id":"https:\/\/www.mid-electronique.com\/es#website","url":"https:\/\/www.mid-electronique.com\/es","name":"MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO","description":"","publisher":{"@id":"https:\/\/www.mid-electronique.com\/es#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mid-electronique.com\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mid-electronique.com\/es#organization","name":"MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO","url":"https:\/\/www.mid-electronique.com\/es","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mid-electronique.com\/es#\/schema\/logo\/image\/","url":"https:\/\/www.mid-electronique.com\/wp-content\/uploads\/2023\/11\/logo-MID-Electronique.png","contentUrl":"https:\/\/www.mid-electronique.com\/wp-content\/uploads\/2023\/11\/logo-MID-Electronique.png","width":300,"height":213,"caption":"MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO"},"image":{"@id":"https:\/\/www.mid-electronique.com\/es#\/schema\/logo\/image\/"},"sameAs":["https:\/\/fr.linkedin.com\/company\/mid-electronique"]}]}},"brands":[{"id":35,"name":"GEFRAN","slug":"gefran"}],"_links":{"self":[{"href":"https:\/\/www.mid-electronique.com\/es\/wp-json\/wp\/v2\/product\/16515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mid-electronique.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mid-electronique.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mid-electronique.com\/es\/wp-json\/wp\/v2\/media\/21061"}],"wp:attachment":[{"href":"https:\/\/www.mid-electronique.com\/es\/wp-json\/wp\/v2\/media?parent=16515"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/www.mid-electronique.com\/es\/wp-json\/wp\/v2\/pwb-brand?post=16515"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mid-electronique.com\/es\/wp-json\/wp\/v2\/product_brand?post=16515"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mid-electronique.com\/es\/wp-json\/wp\/v2\/product_cat?post=16515"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mid-electronique.com\/es\/wp-json\/wp\/v2\/product_tag?post=16515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}