{"id":832,"count":11,"description":"","link":"https:\/\/www.mid-electronique.com\/es\/brand\/man-roland","name":"MAN ROLAND","slug":"man-roland","taxonomy":"pwb-brand","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des MAN ROLAND - MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mid-electronique.com\/es\/brand\/man-roland\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des MAN ROLAND - MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mid-electronique.com\/es\/brand\/man-roland\" \/>\n<meta property=\"og:site_name\" content=\"MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mid-electronique.com\/wp-content\/uploads\/2023\/11\/logo-MID-Electronique.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"213\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.mid-electronique.com\/es\/brand\/man-roland\",\"url\":\"https:\/\/www.mid-electronique.com\/es\/brand\/man-roland\",\"name\":\"Archives des MAN ROLAND - MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO\",\"isPartOf\":{\"@id\":\"https:\/\/www.mid-electronique.com\/es#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.mid-electronique.com\/es\/brand\/man-roland#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mid-electronique.com\/es\/brand\/man-roland#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.mid-electronique.com\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MAN ROLAND\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mid-electronique.com\/es#website\",\"url\":\"https:\/\/www.mid-electronique.com\/es\",\"name\":\"MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.mid-electronique.com\/es#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mid-electronique.com\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.mid-electronique.com\/es#organization\",\"name\":\"MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO\",\"url\":\"https:\/\/www.mid-electronique.com\/es\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.mid-electronique.com\/es#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.mid-electronique.com\/wp-content\/uploads\/2023\/11\/logo-MID-Electronique.png\",\"contentUrl\":\"https:\/\/www.mid-electronique.com\/wp-content\/uploads\/2023\/11\/logo-MID-Electronique.png\",\"width\":300,\"height\":213,\"caption\":\"MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO\"},\"image\":{\"@id\":\"https:\/\/www.mid-electronique.com\/es#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/fr.linkedin.com\/company\/mid-electronique\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des MAN ROLAND - MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mid-electronique.com\/es\/brand\/man-roland","og_locale":"es_ES","og_type":"article","og_title":"Archives des MAN ROLAND - MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO","og_url":"https:\/\/www.mid-electronique.com\/es\/brand\/man-roland","og_site_name":"MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO","og_image":[{"width":300,"height":213,"url":"https:\/\/www.mid-electronique.com\/wp-content\/uploads\/2023\/11\/logo-MID-Electronique.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.mid-electronique.com\/es\/brand\/man-roland","url":"https:\/\/www.mid-electronique.com\/es\/brand\/man-roland","name":"Archives des MAN ROLAND - MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO","isPartOf":{"@id":"https:\/\/www.mid-electronique.com\/es#website"},"breadcrumb":{"@id":"https:\/\/www.mid-electronique.com\/es\/brand\/man-roland#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mid-electronique.com\/es\/brand\/man-roland#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.mid-electronique.com\/es"},{"@type":"ListItem","position":2,"name":"MAN ROLAND"}]},{"@type":"WebSite","@id":"https:\/\/www.mid-electronique.com\/es#website","url":"https:\/\/www.mid-electronique.com\/es","name":"MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO","description":"","publisher":{"@id":"https:\/\/www.mid-electronique.com\/es#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mid-electronique.com\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mid-electronique.com\/es#organization","name":"MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO","url":"https:\/\/www.mid-electronique.com\/es","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mid-electronique.com\/es#\/schema\/logo\/image\/","url":"https:\/\/www.mid-electronique.com\/wp-content\/uploads\/2023\/11\/logo-MID-Electronique.png","contentUrl":"https:\/\/www.mid-electronique.com\/wp-content\/uploads\/2023\/11\/logo-MID-Electronique.png","width":300,"height":213,"caption":"MID Electronique - R\u00e9parations \u00e9lectroniques industrielles - MCO"},"image":{"@id":"https:\/\/www.mid-electronique.com\/es#\/schema\/logo\/image\/"},"sameAs":["https:\/\/fr.linkedin.com\/company\/mid-electronique"]}]}},"_links":{"self":[{"href":"https:\/\/www.mid-electronique.com\/es\/wp-json\/wp\/v2\/pwb-brand\/832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mid-electronique.com\/es\/wp-json\/wp\/v2\/pwb-brand"}],"about":[{"href":"https:\/\/www.mid-electronique.com\/es\/wp-json\/wp\/v2\/taxonomies\/pwb-brand"}],"wp:post_type":[{"href":"https:\/\/www.mid-electronique.com\/es\/wp-json\/wp\/v2\/product?pwb-brand=832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}